{"id":4004,"date":"2020-10-19T09:50:44","date_gmt":"2020-10-19T12:50:44","guid":{"rendered":"http:\/\/www.indaial.sc.gov.br\/empreendedor\/?page_id=4004"},"modified":"2020-10-26T12:53:16","modified_gmt":"2020-10-26T15:53:16","slug":"fluxo-abertura-de-empresas","status":"publish","type":"page","link":"http:\/\/www.indaial.sc.gov.br\/empreendedor\/index.php\/fluxo-abertura-de-empresas\/","title":{"rendered":"FLUXO ABERTURA DE EMPRESAS"},"content":{"rendered":"\n<p>Verifique o fluxo dos processos de abertura de empresa em Indaial de acordo com seu porte.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"630\" height=\"1024\" src=\"http:\/\/www.indaial.sc.gov.br\/empreendedor\/wp-content\/uploads\/2020\/10\/Fluxo-Abertura_page-0001-630x1024.jpg\" alt=\"\" class=\"wp-image-4089\" srcset=\"http:\/\/www.indaial.sc.gov.br\/empreendedor\/wp-content\/uploads\/2020\/10\/Fluxo-Abertura_page-0001-630x1024.jpg 630w, http:\/\/www.indaial.sc.gov.br\/empreendedor\/wp-content\/uploads\/2020\/10\/Fluxo-Abertura_page-0001-185x300.jpg 185w, http:\/\/www.indaial.sc.gov.br\/empreendedor\/wp-content\/uploads\/2020\/10\/Fluxo-Abertura_page-0001-768x1248.jpg 768w, http:\/\/www.indaial.sc.gov.br\/empreendedor\/wp-content\/uploads\/2020\/10\/Fluxo-Abertura_page-0001-945x1536.jpg 945w, http:\/\/www.indaial.sc.gov.br\/empreendedor\/wp-content\/uploads\/2020\/10\/Fluxo-Abertura_page-0001-1260x2048.jpg 1260w, http:\/\/www.indaial.sc.gov.br\/empreendedor\/wp-content\/uploads\/2020\/10\/Fluxo-Abertura_page-0001.jpg 1417w\" sizes=\"(max-width: 630px) 100vw, 630px\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img decoding=\"async\" width=\"630\" height=\"1024\" src=\"http:\/\/www.indaial.sc.gov.br\/empreendedor\/wp-content\/uploads\/2020\/10\/Fluxo-Abertura_page-0002-630x1024.jpg\" alt=\"\" class=\"wp-image-4090\" srcset=\"http:\/\/www.indaial.sc.gov.br\/empreendedor\/wp-content\/uploads\/2020\/10\/Fluxo-Abertura_page-0002-630x1024.jpg 630w, http:\/\/www.indaial.sc.gov.br\/empreendedor\/wp-content\/uploads\/2020\/10\/Fluxo-Abertura_page-0002-185x300.jpg 185w, http:\/\/www.indaial.sc.gov.br\/empreendedor\/wp-content\/uploads\/2020\/10\/Fluxo-Abertura_page-0002-768x1248.jpg 768w, http:\/\/www.indaial.sc.gov.br\/empreendedor\/wp-content\/uploads\/2020\/10\/Fluxo-Abertura_page-0002-945x1536.jpg 945w, http:\/\/www.indaial.sc.gov.br\/empreendedor\/wp-content\/uploads\/2020\/10\/Fluxo-Abertura_page-0002-1260x2048.jpg 1260w, http:\/\/www.indaial.sc.gov.br\/empreendedor\/wp-content\/uploads\/2020\/10\/Fluxo-Abertura_page-0002.jpg 1417w\" sizes=\"(max-width: 630px) 100vw, 630px\" \/><\/figure><\/div>\n\n\n\n<p><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img decoding=\"async\" width=\"630\" height=\"1024\" src=\"http:\/\/www.indaial.sc.gov.br\/empreendedor\/wp-content\/uploads\/2020\/10\/Fluxo-Abertura_page-0003-630x1024.jpg\" alt=\"\" class=\"wp-image-4091\" srcset=\"http:\/\/www.indaial.sc.gov.br\/empreendedor\/wp-content\/uploads\/2020\/10\/Fluxo-Abertura_page-0003-630x1024.jpg 630w, http:\/\/www.indaial.sc.gov.br\/empreendedor\/wp-content\/uploads\/2020\/10\/Fluxo-Abertura_page-0003-185x300.jpg 185w, http:\/\/www.indaial.sc.gov.br\/empreendedor\/wp-content\/uploads\/2020\/10\/Fluxo-Abertura_page-0003-768x1248.jpg 768w, http:\/\/www.indaial.sc.gov.br\/empreendedor\/wp-content\/uploads\/2020\/10\/Fluxo-Abertura_page-0003-945x1536.jpg 945w, http:\/\/www.indaial.sc.gov.br\/empreendedor\/wp-content\/uploads\/2020\/10\/Fluxo-Abertura_page-0003-1260x2048.jpg 1260w, http:\/\/www.indaial.sc.gov.br\/empreendedor\/wp-content\/uploads\/2020\/10\/Fluxo-Abertura_page-0003.jpg 1417w\" sizes=\"(max-width: 630px) 100vw, 630px\" \/><\/figure><\/div>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Verifique o fluxo dos processos de abertura de empresa em Indaial de acordo com seu porte.<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-4004","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"http:\/\/www.indaial.sc.gov.br\/empreendedor\/index.php\/wp-json\/wp\/v2\/pages\/4004","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.indaial.sc.gov.br\/empreendedor\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"http:\/\/www.indaial.sc.gov.br\/empreendedor\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"http:\/\/www.indaial.sc.gov.br\/empreendedor\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.indaial.sc.gov.br\/empreendedor\/index.php\/wp-json\/wp\/v2\/comments?post=4004"}],"version-history":[{"count":3,"href":"http:\/\/www.indaial.sc.gov.br\/empreendedor\/index.php\/wp-json\/wp\/v2\/pages\/4004\/revisions"}],"predecessor-version":[{"id":4092,"href":"http:\/\/www.indaial.sc.gov.br\/empreendedor\/index.php\/wp-json\/wp\/v2\/pages\/4004\/revisions\/4092"}],"wp:attachment":[{"href":"http:\/\/www.indaial.sc.gov.br\/empreendedor\/index.php\/wp-json\/wp\/v2\/media?parent=4004"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}